{"id":11193,"date":"2023-08-24T19:49:28","date_gmt":"2023-08-24T22:49:28","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=11193"},"modified":"2023-08-24T19:49:32","modified_gmt":"2023-08-24T22:49:32","slug":"el-imusa-intensifico-acciones-preventivas-en-itaembe-guazu","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/el-imusa-intensifico-acciones-preventivas-en-itaembe-guazu\/","title":{"rendered":"El IMuSA intensific\u00f3 acciones preventivas en Itaemb\u00e9 Guaz\u00fa"},"content":{"rendered":"\n<p>Con la finalidad de salvaguardar la salud de la comunidad, el Instituto Municipal de Sanidad Animal prosigui\u00f3 con su operativo en el Barrio Itaemb\u00e9 Guaz\u00fa, como parte de las acciones coordinadas por el Municipio. El objetivo central de esta operaci\u00f3n ha sido abordar y prevenir la propagaci\u00f3n de la leishmaniasis, una enfermedad transmitida por vectores que afecta tanto a humanos como a animales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"657\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-24-at-18.57.39.jpeg\" alt=\"\" class=\"wp-image-11194\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-24-at-18.57.39.jpeg 720w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-24-at-18.57.39-300x274.jpeg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>A lo largo de esta jornada, se han implementado diversas medidas preventivas y de control, en un esfuerzo concertado para proteger a los residentes y sus mascotas. Entre las acciones destacadas realizadas por el equipo de IMuSA se encuentran la administraci\u00f3n de 30 dosis de vacuna antirr\u00e1bica, la realizaci\u00f3n de 40 desparasitaciones internas y externas en animales, y la toma de 25 muestras destinadas al testeo de esta enfermedad.<\/p>\n\n\n\n<p>Mientras que, la Direcci\u00f3n de Epidemiolog\u00eda y Vigilancia de la Salud continuar\u00e1 colocando trampas de luz para fleb\u00f3tomo y otros puntos clave del barrio, que permitir\u00e1 la captura segura de insectos para su posterior identificaci\u00f3n en laboratorio.<\/p>\n\n\n\n<p>La Secretar\u00eda de Salud y Desarrollo Humano de Posadas ha enfocado sus acciones en la prevenci\u00f3n y control de esta enfermedad, reconociendo la importancia de abordarla de manera integral y colaborativa. Estos operativos, que se han desarrollado durante este jueves y mi\u00e9rcoles, tambi\u00e9n buscaron concientizar a la comunidad sobre medidas preventivas claves, como mantener un entorno limpio que limite la reproducci\u00f3n de los vectores y resguardar a las mascotas.<\/p>\n\n\n\n<p>La presencia del IMuSA en el Barrio Itaemb\u00e9 Guaz\u00fa refleja el compromiso de la Comuna para garantizar la salud y el bienestar de sus habitantes. Las tareas conjuntas de las autoridades sanitarias y la comunidad son esenciales para minimizar el impacto de la leishmaniasis y prevenir su propagaci\u00f3n. Ya que se trata de una enfermedad transmitida a trav\u00e9s de la picadura de fleb\u00f3tomos, peque\u00f1os insectos, que pueden transmitirla tanto a humanos como a animales dom\u00e9sticos.<\/p>\n\n\n\n<p>Las autoridades sanitarias instan a los residentes de Posadas a participar activamente en estos esfuerzos preventivos. El compromiso continuo con la salud p\u00fablica demuestra que, a trav\u00e9s de la cooperaci\u00f3n entre el Municipio y los vecinos, es posible mitigar los riesgos asociados con enfermedades transmitidas por vectores como la leishmaniasis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de salvaguardar la salud de la comunidad, el Instituto Municipal de Sanidad Animal prosigui&oacute; con su operativo en el Barrio Itaemb&eacute; Guaz&uacute;, como parte de las acciones&hellip; <\/p>\n","protected":false},"author":3,"featured_media":11195,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[3],"tags":[22],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/11193"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=11193"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/11193\/revisions"}],"predecessor-version":[{"id":11196,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/11193\/revisions\/11196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/11195"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=11193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=11193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=11193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}