{"id":26752,"date":"2024-09-30T08:27:00","date_gmt":"2024-09-30T11:27:00","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=26752"},"modified":"2024-09-30T08:27:12","modified_gmt":"2024-09-30T11:27:12","slug":"en-lo-que-va-del-ano-el-gobierno-de-misiones-destino-mas-de-103-mil-millones-en-creditos-para-potenciar-la-produccion-y-las-pymes-misioneras","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/en-lo-que-va-del-ano-el-gobierno-de-misiones-destino-mas-de-103-mil-millones-en-creditos-para-potenciar-la-produccion-y-las-pymes-misioneras\/","title":{"rendered":"En lo que va del a\u00f1o, el gobierno de Misiones destin\u00f3 m\u00e1s de $103 mil millones en cr\u00e9ditos para potenciar la producci\u00f3n y las pymes misioneras"},"content":{"rendered":"\n<p>El Gobierno de Misiones ha destinado, en lo que va del a\u00f1o, m\u00e1s de 103 mil millones de pesos en cr\u00e9ditos con tasas subsidiadas para impulsar la producci\u00f3n y fortalecer a las PyMEs. As\u00ed, a trav\u00e9s de organismos provinciales como el IMAC, el Fondo de Cr\u00e9dito, o trabajando en conjunto con entidades bancarias como el Banco Macro y el Banco Naci\u00f3n, la Provincia acompa\u00f1a en su crecimiento a todos los sectores de la econom\u00eda misionera. Adem\u00e1s, la semana pasada se confirm\u00f3 la continuidad de la l\u00ednea de cr\u00e9ditos productivos que ofrece Misiones en conjunto con el Banco Macro a Micro, Peque\u00f1as y Medianas Empresas (MiPyME).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-30-at-08.21.41-1024x682.jpeg\" alt=\"\" class=\"wp-image-26753\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-30-at-08.21.41-1024x682.jpeg 1024w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-30-at-08.21.41-300x200.jpeg 300w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-30-at-08.21.41-768x512.jpeg 768w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-30-at-08.21.41.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p> Recientemente, el Gobierno de la Provincia ampli\u00f3 las opciones crediticias para distintos sectores productivos, lanzando seis nuevas l\u00edneas de cr\u00e9dito en colaboraci\u00f3n con el Banco Naci\u00f3n. Estas incluyen un monto total de 80.000 millones de pesos, con tasas bonificadas entre el 18% y el 37%, las cuales est\u00e1n destinadas a fortalecer la capacidad exportadora de las PyMEs, impulsar la econom\u00eda del conocimiento y la inversi\u00f3n en maquinarias agr\u00edcolas, entre otros sectores. La primera l\u00ednea ofrece hasta 20 millones de pesos por empresa para capital de trabajo, mientras que la l\u00ednea m\u00e1s significativa, enfocada en la energ\u00eda basada en biomasa, permite acceder a hasta 3.800 millones de pesos por empresa.<\/p>\n\n\n\n<p>En el marco de su lanzamiento, el Ministerio de Hacienda inform\u00f3 que hay cerca de 100 empresas misioneras que est\u00e1n interesadas en capitalizarse y acceder a estos cr\u00e9ditos. Estos beneficios est\u00e1n habilitados desde la semana pasada, las empresas interesadas pueden acercarse a cualquier sucursal del Banco Naci\u00f3n y ya pueden comenzar a tramitar la l\u00ednea crediticia.<\/p>\n\n\n\n<p>As\u00ed, junto a dicha iniciativa y otras similares hasta la fecha, el Gobierno de Misiones ya ha destinado 103 mil millones de pesos en cr\u00e9ditos con tasas subsidiadas. Estos financiamientos, canalizados a trav\u00e9s del trabajo conjunto con el Banco Macro y el Banco Naci\u00f3n, el CFI, y organismos provinciales como el Instituto de Macroeconom\u00eda Circular (IMAC) y el Fondo de Cr\u00e9dito, buscan brindar soporte financiero a quienes est\u00e1n produciendo, facilitando la reactivaci\u00f3n, ampliaci\u00f3n o apertura de nuevos negocios.<\/p>\n\n\n\n<p>CAPITAL DE TRABAJO Y BENEFICIOS PARA PYMES<\/p>\n\n\n\n<p>Justamente, esta gesti\u00f3n comenz\u00f3 en febrero, con la firma de un convenio con el Consejo Federal de Inversiones (CFI), que estableci\u00f3 l\u00edneas de cr\u00e9dito orientadas a todos los sectores productivos, con tasas de inter\u00e9s competitivas y plazos de hasta 84 meses. Las empresas pueden acceder a un m\u00e1ximo de 120 millones de pesos por entidad. Adem\u00e1s, el Fondo de Cr\u00e9dito de Misiones act\u00faa como ventanilla de recepci\u00f3n de solicitudes, centralizando la gesti\u00f3n de los pr\u00e9stamos.<\/p>\n\n\n\n<p>En detalle, en el mes de junio, el Fondo de Cr\u00e9dito present\u00f3 el programa \u201cCapital de Trabajo\u201d, que ofrece hasta 2 millones de pesos en financiamiento, con una tasa de inter\u00e9s subsidiada del 43% de la Tasa Badlar. Este programa est\u00e1 dise\u00f1ado para proporcionar liquidez a emprendedores y empresas, facilitando la compra de insumos y materias primas. El plazo de devoluci\u00f3n es de hasta 12 meses, con flexibilidad en las garant\u00edas.<\/p>\n\n\n\n<p>Vale recordar que el Fondo de Cr\u00e9dito de Misiones ofrece actualmente cinco l\u00edneas de financiamiento: capital de trabajo, capital fijo, formaci\u00f3n profesional, audiovisual y recr\u00e9dito. Los interesados en acceder a estas opciones pueden ingresar en https:\/\/fondocreditomisiones.gob.ar\/asistencia-crediticia\/, donde encontrar\u00e1n los requisitos, condiciones y tasas de inter\u00e9s actualizadas. En la secci\u00f3n de financiamiento, se dispone de infograf\u00edas detalladas y un bot\u00f3n para iniciar la solicitud. Al completar el formulario en l\u00ednea, la solicitud ser\u00e1 gestionada por un oficial de cr\u00e9dito, quien se pondr\u00e1 en contacto en breve.<\/p>\n\n\n\n<p>En cuanto a las PyMEs, la L\u00ednea de Cr\u00e9ditos Productivos del Banco Macro, en su primer tramo, lanzado en junio con un cupo de 4.000 millones de pesos, se agot\u00f3 en solo 20 d\u00edas, y benefici\u00f3 a 131 empresas. El segundo tramo, con un cupo de 1.500 millones, se adjudic\u00f3 en julio, con 80 cr\u00e9ditos aprobados. En agosto, se lanz\u00f3 el tercer tramo de la misma, con un cupo de 1.500 millones de pesos, destinado a empresas de todos los sectores con el certificado MiPyME.<\/p>\n\n\n\n<p>Adem\u00e1s, la semana pasada se lanz\u00f3 el cuarto tramo que cuenta con un monto total de $1.500 millones, estar\u00e1 disponible desde hoy mi\u00e9rcoles 24 de septiembre y se extender\u00e1 hasta el 31 de diciembre de 2024. En esta oportunidad, las empresas MiPyME de Misiones podr\u00e1n acceder a cr\u00e9ditos de hasta $80 millones por empresa para capital de trabajo, con una tasa anual bonificada por el Gobierno de Misiones del 41,5% TNA y un plazo de pago de 13 meses.<\/p>\n\n\n\n<p>Estos pr\u00e9stamos tienen un tope de 80 millones de pesos por empresa, con una tasa bonificada del 38,5% TNA, y un plazo de devoluci\u00f3n de 13 meses.<\/p>\n\n\n\n<p>SECTOR AGROINDUSTRIAL<\/p>\n\n\n\n<p>Para el sector agroindustrial, en junio se formaliz\u00f3 un convenio con el Banco Naci\u00f3n que lanz\u00f3 nuevas l\u00edneas de cr\u00e9dito dirigidas a las industrias yerbatera y forestal. \u00c9stas incluyen un total de 5.000 millones de pesos para el sector yerbatero, con una tasa del 26% bonificada en 10 puntos por el gobierno provincial. Cada empresa podr\u00e1 acceder a hasta 80 millones de pesos, garantizados con Warrants. Por su parte, el sector forestal accedi\u00f3 a una l\u00ednea de cr\u00e9dito de 4.000 millones de pesos, tambi\u00e9n con tasas bonificadas y garant\u00edas a elecci\u00f3n del Banco Naci\u00f3n.<\/p>\n\n\n\n<p>En julio, se ampliaron los cr\u00e9ditos yerbateros, incrementando el monto por empresa a 400 millones de pesos, con una tasa nominal anual del 19%, subsidiada por el gobierno. Esta medida apunta a estabilizar los precios de la yerba mate y apoyar a las empresas del sector en un contexto econ\u00f3mico desafiante.<\/p>\n\n\n\n<p>Para consultar la vigencia de estas l\u00edneas y sus requisitos de acceso para pymes o empresas, el Ministerio de Hacienda recomienda a los interesados acercarse a las sucursales de las entidades crediticias responsables del financiamiento de las mismas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Misiones ha destinado, en lo que va del a&ntilde;o, m&aacute;s de 103 mil millones de pesos en cr&eacute;ditos con tasas subsidiadas para impulsar la producci&oacute;n y fortalecer&hellip; <\/p>\n","protected":false},"author":3,"featured_media":26754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[3],"tags":[217],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/26752"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=26752"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/26752\/revisions"}],"predecessor-version":[{"id":26755,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/26752\/revisions\/26755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/26754"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=26752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=26752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=26752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}