{"id":30212,"date":"2025-02-13T07:01:24","date_gmt":"2025-02-13T10:01:24","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=30212"},"modified":"2025-02-13T07:01:29","modified_gmt":"2025-02-13T10:01:29","slug":"santo-pipo-familias-agricultoras-de-carlos-car-reclaman-arreglo-de-bomba-estan-sin-agua-desde-hace-meses%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/santo-pipo-familias-agricultoras-de-carlos-car-reclaman-arreglo-de-bomba-estan-sin-agua-desde-hace-meses%ef%bf%bc\/","title":{"rendered":"Santo Pip\u00f3: Familias agricultoras de Carlos Car reclaman arreglo de bomba, est\u00e1n sin agua desde hace meses\ufffc"},"content":{"rendered":"\n<p>SANTO PIP\u00d3. En el peque\u00f1o paraje Carlos Car, del Municipio de Santo Pip\u00f3, m\u00e1s de 30 familias llevan varios meses sin el abastecimiento del agua potable, porque desde el a\u00f1o pasado en que se rompi\u00f3 la bomba, las autoridades municipales no se ocupan de mandar a repararla.<br>Eso genera que las familias tengan que caminar largos kil\u00f3metros para conseguir agua, en plena sequ\u00eda y emergencia clim\u00e1tica.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"958\" height=\"1024\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/02\/La-falta-de-agua-afecta-epecialmente-a-ninos-ninas-y-adultos-mayores.-958x1024.jpg\" alt=\"\" class=\"wp-image-30213\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/02\/La-falta-de-agua-afecta-epecialmente-a-ninos-ninas-y-adultos-mayores.-958x1024.jpg 958w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/02\/La-falta-de-agua-afecta-epecialmente-a-ninos-ninas-y-adultos-mayores.-281x300.jpg 281w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/02\/La-falta-de-agua-afecta-epecialmente-a-ninos-ninas-y-adultos-mayores.-768x821.jpg 768w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/02\/La-falta-de-agua-afecta-epecialmente-a-ninos-ninas-y-adultos-mayores..jpg 1200w\" sizes=\"(max-width: 958px) 100vw, 958px\" \/><\/figure>\n\n\n\n<p><br>Dami\u00e1n Rojas vive en Carlos Car desde hace muchos a\u00f1os, y padece la falta del l\u00edquido vital, como el resto de sus vecinos. \u00abNo podemos confiar en el agua que reparten los camiones porque es insalubre, y afect\u00f3 a los m\u00e1s chicos, entre ellos mi hija de 10 a\u00f1os, que por el malestar no pudo actuar en el acto escolar de fin de a\u00f1o. Se que varios sufrieron problemas estomacales, con v\u00f3mitos y fiebre\u00bb.\u00a0<\/p>\n\n\n\n<p>Ante este riesgo, no les queda otra alternativa que recorrer esos kil\u00f3metros y con un camino en muy malas condiciones para traer agua sana desde la capilla, es el \u00fanico lugar que tiene una perforaci\u00f3n y les permiten compartir. \u00abSin agua y con este calor es terrible vivir as\u00ed, sobre todo con los chicos\u00bb, se quej\u00f3 el padre de tres hijos.<\/p>\n\n\n\n<p>Dami\u00e1n relat\u00f3 que hubo un intento de soluci\u00f3n el a\u00f1o pasado en octubre, cuando desde la Comuna hicieron el intento de un nuevo pozo; pero dejaron la obra inconclusa, sin terminar de colocar los ca\u00f1os, y con una perforaci\u00f3n a medias. Los vecinos reclamaron a la Municipalidad, administrada&nbsp;por la profesora Claudia Acu\u00f1a (FR); pero hasta ahora no hubo respuestas a&nbsp;la demanda.<\/p>\n\n\n\n<p><strong>\u00abEn Pip\u00f3 no existe pol\u00edtica rural ni de desarrollo agropecuario\u00bb<\/strong><br>En una de las recorridas que el dirigente del Partido<strong><em> Tierra, Techo y Trabajo<\/em><\/strong>, Mart\u00edn Sereno realiza frecuentemente por la provincia, se reuni\u00f3 con las familias de Carlos Car que est\u00e1n desesperadas. &nbsp;<br>Esta picada est\u00e1 integrada por familias campesinas de la agricultura familiar, con peque\u00f1as producciones. \u00abEs inconcebible que pasados tres meses de haberse roto la bomba del pozo que abastece a la comunidad, y los responsables&nbsp;municipales no lo hayan resuelto, aunque hubo un intento de repararlo\u00bb, dijo.<br>Es un pozo que qued\u00f3 vetusto porque aument\u00f3 la cantidad de habitantes, y ahora todos sufren la carencia del suministro de agua potable. Sereno acot\u00f3 que en este verano, uno de los m\u00e1s t\u00f3rridos que sufri\u00f3 la provincia en los \u00faltimos a\u00f1os, con sensaciones t\u00e9rmicas que superan ampliamente los 40 grados, la producci\u00f3n de agua es fundamental para la salud de las personas, y en casos como \u00e9ste, adem\u00e1s perjudica a la producci\u00f3n.<br>\u00abHicimos una recorrida y nos encontramos con casos de intoxicaci\u00f3n por agua insalubre, y familias que deben recorrer muchos kil\u00f3metros para conseguir agua sana. Hay lactantes, adultos mayores que sufren la problem\u00e1tica sin que el municipio reaccione, da la impresi\u00f3n de que est\u00e1n de vacaciones\u00bb, cuestion\u00f3.<br>El dirigente del Movimiento Evita reclam\u00f3&nbsp;que en Carlos Car los caminos tampoco se encuentran en buenas condiciones. \u00abEs evidente que no hay una pol\u00edtica campesina o rural; de desarrollo agropecuario ni de agricultura familiar en este municipio, porque son varios los parajes que recorremos y el campesinado nos manifiesta que no tienen respaldo, fomento, apoyo; no existe desarrollo productivo, ni la garant\u00eda de derechos b\u00e1sicos como agua y caminos\u00bb.<\/p>\n\n\n\n<p>Junto a los militantes, el dirigente inici\u00f3 gestiones con las instituciones provinciales pertinentes, a quienes manifestaron la urgencia para lograr una soluci\u00f3n, y solicitaron que act\u00faen r\u00e1pidamente.<br><strong><br>\u00abEs inhumano que tengamos que vivir as\u00ed\u00bb<\/strong><br>Cecilia es una madre preocupada porque tiene una hija, Victoria, de pocos&nbsp;meses a&nbsp;la que amamanta, y la falta de agua es un verdadero problema que requiere atenci\u00f3n.<br>Esta familia de agricultores, como otros del paraje, necesitan y reclaman que desde el Municipio \u00abo el organismo que sea\u00bb, les brinden una soluci\u00f3n porque son muchos meses padeciendo esa carencia.<br>\u00abVamos y venimos tres kil\u00f3metros hasta la capilla, para buscar agua cargando bidones y botellas. Es inhumano que tengamos que vivir as\u00ed, sobre todo cuando hay tantos chicos y abuelos en la picada, y cuando nuestros hijos se enferman, por ejemplo por tomar agua insalubre, como ya pas\u00f3, no tenemos un Centro de Salud cerca para recurrir, y a los padres no nos queda otra que&nbsp;viajar hasta el Hospital de Gobernador Roca, lament\u00f3 Cecilia.<\/p>\n\n\n\n<p>Los vecinos destacaron que en el paraje tambi\u00e9n existen problemas con la energ\u00eda el\u00e9ctrica. Semanas atr\u00e1s se quem\u00f3 un cable de alta tensi\u00f3n, y provoc\u00f3 un incendio entre los \u00e1rboles, sin que acudiera alguna otra autoridad para evaluar qu\u00e9 pasaba. Afortunadamente en esos d\u00edas llovi\u00f3, y ese efecto clim\u00e1tico apag\u00f3 el fuego; pero el cable qued\u00f3 tirado en la ruta.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO PIP&Oacute;. En el peque&ntilde;o paraje Carlos Car, del Municipio de Santo Pip&oacute;, m&aacute;s de 30 familias llevan varios meses sin el abastecimiento del agua potable, porque desde el a&ntilde;o&hellip; <\/p>\n","protected":false},"author":3,"featured_media":30214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[3],"tags":[322],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/30212"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=30212"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/30212\/revisions"}],"predecessor-version":[{"id":30215,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/30212\/revisions\/30215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/30214"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=30212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=30212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=30212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}