{"id":34030,"date":"2025-07-07T07:22:57","date_gmt":"2025-07-07T10:22:57","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=34030"},"modified":"2025-07-07T07:23:28","modified_gmt":"2025-07-07T10:23:28","slug":"misiones-impulsa-una-red-de-vigilancia-para-prevenir-enfermedades-transmitidas-por-mosquitos","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/misiones-impulsa-una-red-de-vigilancia-para-prevenir-enfermedades-transmitidas-por-mosquitos\/","title":{"rendered":"Misiones impulsa una red de vigilancia para prevenir enfermedades transmitidas por mosquitos"},"content":{"rendered":"\n<p>El proyecto cuenta con la participaci\u00f3n de municipios, el Ministerio de Salud P\u00fablica y la Agencia Misionera de Innovaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"800\" height=\"533\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/07\/Red-de-vigilancia-4.jpeg\" alt=\"\" class=\"wp-image-34031\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/07\/Red-de-vigilancia-4.jpeg 800w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/07\/Red-de-vigilancia-4-300x200.jpeg 300w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2025\/07\/Red-de-vigilancia-4-768x512.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Se pone en marcha el proyecto para crear una red provincial de vigilancia entomol\u00f3gica que<br>permita anticipar y controlar brotes de enfermedades como dengue, chikungunya, zika y fiebre<br>amarilla. Dicho proyecto se enmarca en el Plan Estrat\u00e9gico de Abordaje integral de las<\/p>\n\n\n\n<p>Arbovirosis 2023\/2027<\/p>\n\n\n\n<p><br>La iniciativa, desarrollado entre el Ministerio de Salud P\u00fablica y la Agencia Misionera de<br>Innovaci\u00f3n, cuenta con la participaci\u00f3n activa de las municipalidades de Posadas, Eldorado,<br>Ober\u00e1 y Comandante Andresito, se centra en el uso de sensores de oviposici\u00f3n, una tecnolog\u00eda<br>eficaz para monitorear la presencia del mosquito Aedes aegypti. Este m\u00e9todo permite detectar<br>con precisi\u00f3n la abundancia del vector y generar informaci\u00f3n clave para la toma de decisiones<br>sanitarias.<br>La ejecuci\u00f3n del proyecto contempla cinco etapas centrales que se desarrollan de forma<br>progresiva: en primer lugar, se realiza un diagn\u00f3stico local para relevar las capacidades, recursos<br>y estrategias existentes en los municipios en relaci\u00f3n al control del mosquito. Luego, se lleva<br>adelante la capacitaci\u00f3n y transferencia de conocimientos a equipos t\u00e9cnicos, abordando el uso<br>de sensores, an\u00e1lisis de datos y trabajo comunitario. En una tercera etapa, se crea un sistema de<br>registro provincial mediante una plataforma digital que permite sistematizar e interpretar la<br>informaci\u00f3n recolectada. Posteriormente, se eval\u00faa el proceso de manera integral para mejorar<br>los procedimientos y garantizar la sostenibilidad de la estrategia. Finalmente, se elabora un<br>informe t\u00e9cnico con los resultados y se realiza una presentaci\u00f3n oficial del sistema provincial de<br>vigilancia entomol\u00f3gica.<br>Este proyecto no s\u00f3lo apunta a una mejora operativa en la prevenci\u00f3n de enfermedades<br>vectoriales, sino tambi\u00e9n a un fortalecimiento institucional. En este sentido, se destaca el rol del<br>\u00c1rea de Investigaci\u00f3n para la Salud del Ministerio, que trabaja para consolidar un sistema<br>cient\u00edfico que respalde las pol\u00edticas p\u00fablicas sanitarias.<br>La Agencia Misionera de Innovaci\u00f3n tuvo un papel clave en la gesti\u00f3n de financiamiento para la<br>compra de equipamientos tecnol\u00f3gicos necesarios para llevar adelante el plan, incluyendo<br>computadoras, lupas estereosc\u00f3picas, c\u00e1maras, sensores y materiales de laboratorio.<br>\u201cLa articulaci\u00f3n entre salud, ciencia y tecnolog\u00eda es clave para responder a los desaf\u00edos sanitarios<br>que impone el cambio clim\u00e1tico y la movilidad poblacional en nuestra regi\u00f3n\u201d, afirm\u00f3 Fabi\u00e1n<br>Zelaya, director del proyecto.<br>El proyecto busca consolidar y ampliar la alianza estrat\u00e9gica entre salud, ciencia, tecnolog\u00eda e<br>innovaci\u00f3n, se inscribe en la l\u00ednea del vector Salud y Ambiente seg\u00fan la Agenda Territorial<br>Integradora de la provincia de Misiones, en investigaci\u00f3n y transferencia de tecnolog\u00eda para la<br>evaluaci\u00f3n del impacto de variables ambientales y reemergencia de enfermedades infecciosas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto cuenta con la participaci&oacute;n de municipios, el Ministerio de Salud P&uacute;blica y la Agencia Misionera de Innovaci&oacute;n. Se pone en marcha el proyecto para crear una red provincial&hellip; <\/p>\n","protected":false},"author":3,"featured_media":34032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[3],"tags":[19],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/34030"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=34030"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/34030\/revisions"}],"predecessor-version":[{"id":34033,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/34030\/revisions\/34033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/34032"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=34030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=34030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=34030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}