{"id":6783,"date":"2023-03-13T17:36:14","date_gmt":"2023-03-13T20:36:14","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=6783"},"modified":"2023-03-13T17:36:19","modified_gmt":"2023-03-13T20:36:19","slug":"liraa-mas-de-1-600-hogares-visitados-continua-el-monitoreo-del-aedes","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/liraa-mas-de-1-600-hogares-visitados-continua-el-monitoreo-del-aedes\/","title":{"rendered":"LIRAa: M\u00e1s de 1.600 hogares visitados, contin\u00faa el monitoreo del Aedes"},"content":{"rendered":"\n<p>La XXXVII edici\u00f3n del operativo LIRAa (Levantamiento de \u00cdndices R\u00e1pidos de Aedes aegypti) se desarrolla en los barrios con el objetivo de recolectar informaci\u00f3n sobre la presencia del mosquito transmisor de enfermedades vectoriales. En dos d\u00edas, los equipos municipales ingresaron a 1.650 casas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"810\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-13-at-15.23.40-1024x810.jpeg\" alt=\"\" class=\"wp-image-6785\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-13-at-15.23.40-1024x810.jpeg 1024w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-13-at-15.23.40-300x237.jpeg 300w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-13-at-15.23.40-768x607.jpeg 768w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-13-at-15.23.40.jpeg 1185w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Las actividades consistieron en realizar una inspecci\u00f3n minuciosa del domicilio y peridomicilio (patio, terraza, jard\u00edn) para identificar los posibles criaderos de larvas de este insecto. Los t\u00e9cnicos registraron la cantidad y tipos de recipientes encontrados, como tambi\u00e9n tomaron muestras para su posterior an\u00e1lisis.<\/p>\n\n\n\n<p>Durante el relevamiento, los equipos dialogaron con los vecinos para explicar las medidas preventivas, la importancia de la descacharrizaci\u00f3n como tambi\u00e9n de mantener limpios y sin agua los lugares para que el Aedes aegypti evitara depositar sus huevos.<\/p>\n\n\n\n<p>Estas acciones preventivas se realizaron en los barrios correspondientes a las Delegaciones Municipales de Miguel Lan\u00fas, Villa Urquiza, Riberas del Paran\u00e1 y Centro. Mientras que, este lunes el relevamiento se lleva adelante en las jurisdicciones de Villa Cabello, Riberas del Paran\u00e1 y Santa Rita.<\/p>\n\n\n\n<p>LIRAa es el nombre utilizado para designar al m\u00e9todo de monitoreo que puede realizarse r\u00e1pidamente a fin de identificar los criaderos del Aedes aegypti, lo que permite establecer los riesgos para la comunidad. En Posadas este operativo se realiza desde 2009. Por ello, es muy importante la colaboraci\u00f3n de los vecinos para que permitan el ingreso de los agentes municipales a sus viviendas para que tomen el muestreo.<\/p>\n\n\n\n<p>Los t\u00e9cnicos se encuentran debidamente identificados con indumentarias de la gesti\u00f3n municipal y credencial en la que se detallan los datos personales. Ante cualquier duda, los vecinos pueden comunicarse a los tel\u00e9fonos 44-20183 y 15-4731040 del Instituto Municipal de Vigilancia y Control de Vectores; o bien; al 0800-888-2483 del Centro de Atenci\u00f3n al Ciudadano, de lunes a viernes, de 7 a 19 hs.<\/p>\n\n\n\n<p>CRONOGRAMA: El monitoreo se realiza de 08:00 a 13:00 hs y de 14:00 a 19:00 hs.<\/p>\n\n\n\n<p>\ud83d\uddd3\ufe0f MARTES 14\/03: Delegaciones parte de Santa Rita, 32-33 e Itaemb\u00e9 Min\u00ed Oeste.<\/p>\n\n\n\n<p>\ud83d\uddd3\ufe0f MI\u00c9RCOLES 15\/03: Delegaciones de Itaemb\u00e9 Min\u00ed Este, Itaemb\u00e9 Min\u00ed Oeste, Dolores Norte y Dolores Sur.<\/p>\n\n\n\n<p>\ud83d\uddd3\ufe0f JUEVES 16\/03: Delegaciones de Itaemb\u00e9 Min\u00ed Este, Itaemb\u00e9 Min\u00ed Oeste, Miguel Lan\u00fas e Itaemb\u00e9 Guaz\u00fa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La XXXVII edici&oacute;n del operativo LIRAa (Levantamiento de &Iacute;ndices R&aacute;pidos de Aedes aegypti) se desarrolla en los barrios con el objetivo de recolectar informaci&oacute;n sobre la presencia del mosquito transmisor&hellip; <\/p>\n","protected":false},"author":3,"featured_media":6784,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[3],"tags":[22],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/6783"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=6783"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/6783\/revisions"}],"predecessor-version":[{"id":6786,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/6783\/revisions\/6786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/6784"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=6783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=6783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=6783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}