{"id":7234,"date":"2023-03-31T07:55:56","date_gmt":"2023-03-31T10:55:56","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=7234"},"modified":"2023-03-31T07:56:00","modified_gmt":"2023-03-31T10:56:00","slug":"despues-de-la-lluvia-es-conveniente-reforzar-la-prevencion-para-que-no-se-multipliquen-los-mosquitos","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/despues-de-la-lluvia-es-conveniente-reforzar-la-prevencion-para-que-no-se-multipliquen-los-mosquitos\/","title":{"rendered":"Despu\u00e9s de la lluvia es conveniente reforzar la prevenci\u00f3n para que no se multipliquen los mosquitos"},"content":{"rendered":"\n<p>Luego de las precipitaciones, se solicita a los vecinos incrementar las medidas preventivas para evitar la proliferaci\u00f3n del mosquito Aedes aegypti, transmisor de enfermedades como el dengue, el zika y la fiebre amarilla, chikungunya. Por este motivo, resulta fundamental limpiar y vaciar cualquier recipiente que pueda acumular agua.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"577\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-30-at-11.35.50.jpeg\" alt=\"\" class=\"wp-image-7235\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-30-at-11.35.50.jpeg 720w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-30-at-11.35.50-300x240.jpeg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>Vale resaltar que durante todo el a\u00f1o, los agentes municipales trabajan para controlar la reproducci\u00f3n de este insecto vector de enfermedades, buscando mejorar la calidad de vida de las familias posade\u00f1as. La ejecuci\u00f3n de estas pol\u00edticas p\u00fablicas sanitarias tiene como objetivo prevenir la propagaci\u00f3n de casos de dengue y para ello, se intensifican los trabajos preventivos casa por casa. El accionar consiste principalmente en el control focal, por medio del cual se permite identificar y eliminar los posibles criaderos.<\/p>\n\n\n\n<p>Por ello, es importante destapar los desag\u00fces de lluvia de los techos, pozos, letrinas abandonadas, mantener limpios los patios de las viviendas, recoger los residuos s\u00f3lidos en predios y lotes bald\u00edos. Tambi\u00e9n se recomienda la vigilancia de los espacios naturales que puedan constituirse en criaderos como huecos de \u00e1rboles, plantas y flores. En tal sentido, es importante mencionar que, cada vecino debe colaborar manteniendo sus patios y jardines limpios, desmalezados y sin elementos que puedan acopiar agua, descartando todos aquellos objetos que no utilicen.<\/p>\n\n\n\n<p>Ante cualquier duda, los vecinos pueden comunicarse a los tel\u00e9fonos 44-20183 del Instituto Municipal de Vigilancia y Control de Vectores o bien al 0800-888-2483 del Centro de Atenci\u00f3n al Ciudadano, de lunes a viernes, de 7 a 19 hs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de las precipitaciones, se solicita a los vecinos incrementar las medidas preventivas para evitar la proliferaci&oacute;n del mosquito Aedes aegypti, transmisor de enfermedades como el dengue, el zika y&hellip; <\/p>\n","protected":false},"author":3,"featured_media":7236,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[3],"tags":[22],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7234"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=7234"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7234\/revisions"}],"predecessor-version":[{"id":7237,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7234\/revisions\/7237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/7236"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=7234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=7234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=7234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}