{"id":7330,"date":"2023-04-04T09:36:19","date_gmt":"2023-04-04T12:36:19","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=7330"},"modified":"2023-04-04T09:36:23","modified_gmt":"2023-04-04T12:36:23","slug":"masiva-presentacion-de-candidatos-de-la-fuerza-de-todos","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/masiva-presentacion-de-candidatos-de-la-fuerza-de-todos\/","title":{"rendered":"Masiva presentaci\u00f3n de candidatos de La Fuerza de Todos"},"content":{"rendered":"\n<p>Este s\u00e1bado hicieron su presentaci\u00f3n en Jard\u00edn Am\u00e9rica candidatos y candidatas de toda la Provincia de Misiones con miras a las elecciones del 7 de mayo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-02-at-11.18.57-1024x682.jpeg\" alt=\"\" class=\"wp-image-7331\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-02-at-11.18.57-1024x682.jpeg 1024w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-02-at-11.18.57-300x200.jpeg 300w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-02-at-11.18.57-768x512.jpeg 768w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-02-at-11.18.57.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><br>El acto fue encabezado por el candidato a gobernador Isaac Lenguaza, presidente del Partido Agrario y Social (PAyS), quien es acompa\u00f1ado en la f\u00f3rmula por el actual diputado provincial Santiago Mansilla como candidato a vicegobernador.<\/p>\n\n\n\n<p><br>Asistieron al encuentro el diputado nacional H\u00e9ctor \u201cCacho\u201d B\u00e1rbaro (Frente de Todos-PAyS), la diputada nacional Cristina Br\u00edtez (Frente de Todos-La C\u00e1mpora), los diputados provinciales Blanca Alvez y Mart\u00edn Sancho, el intendente de Colonia Aurora Carlos \u201cCali\u201d Goring (PAyS), la treintena de actuales concejales del espacio y las y los candidatos a diputados provinciales y quienes integran los cerca de doscientos sublemas inscriptos que competir\u00e1n en las elecciones provinciales en todas las localidades misioneras.<br>El lugar se colm\u00f3 de militantes de los diferentes partidos y espacios pol\u00edticos de La Fuerza de Todos, que representa en Misiones la continuidad del Frente de Todos que triunf\u00f3 en las elecciones nacionales de 2019.<\/p>\n\n\n\n<p><br>\u201cEn unidad para transformar la provincia\u201d fue uno de los lemas remarcados por los oradores al destacar la potencia del armado electoral que alienta a \u201campliar la agenda de la pol\u00edtica\u201d en Misiones con propuestas para los peque\u00f1os productores agropecuarios que no acceden a la titularidad de sus tierras; \u00a0para los trabajadores y trabajadoras sobreendeudados; para los que no logran acceder a una vivienda construida por el Estado y las familias que no tienen apoyo para enfrentar el problema de las adicciones. \u201cEl crecimiento es de abajo hacia arriba y tenemos un plan para eso\u201d, se\u00f1alaron.<\/p>\n\n\n\n<p><br>En un potente discurso, el candidato a gobernador Isaac Lenguaza resalt\u00f3 tambi\u00e9n la trascendencia de enfrentar a las pol\u00edticas que propone la derecha y buscan anular derechos sociales y laborales con una fuerza propia y unida. \u201cLos que no est\u00e1n en este Frente, est\u00e1n con la Renovaci\u00f3n o Cambiemos\u201d dispar\u00f3, y agreg\u00f3 que \u201cnunca fue una opci\u00f3n para nosotros decir que da lo mismo un gobierno u otro\u201d. \u201cLos misioneros tenemos en claro que no vamos a dejar que vuelva un modelo que cierra f\u00e1bricas y emprendimientos, que concentra la riqueza, que no piensa en los j\u00f3venes, en los trabajadores y en los que merecen una vida digna como adultos mayores, y no estamos de acuerdo con un gobierno provincial que se alinea con estas ideas\u201d, finaliz\u00f3.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este s&aacute;bado hicieron su presentaci&oacute;n en Jard&iacute;n Am&eacute;rica candidatos y candidatas de toda la Provincia de Misiones con miras a las elecciones del 7 de mayo. El acto fue encabezado&hellip; <\/p>\n","protected":false},"author":3,"featured_media":7332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[3],"tags":[133],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7330"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=7330"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7330\/revisions"}],"predecessor-version":[{"id":7333,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7330\/revisions\/7333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/7332"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=7330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=7330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=7330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}