{"id":7985,"date":"2023-04-25T19:29:45","date_gmt":"2023-04-25T22:29:45","guid":{"rendered":"https:\/\/radionewsmisiones.ar\/site\/?p=7985"},"modified":"2023-04-25T19:29:50","modified_gmt":"2023-04-25T22:29:50","slug":"el-modelo-de-descentralizacion-y-participacion-ciudadana-de-posadas-se-presentara-ante-funcionarios-y-expertos-mundiales","status":"publish","type":"post","link":"https:\/\/radionewsmisiones.ar\/site\/provinciales\/el-modelo-de-descentralizacion-y-participacion-ciudadana-de-posadas-se-presentara-ante-funcionarios-y-expertos-mundiales\/","title":{"rendered":"El modelo de descentralizaci\u00f3n y participaci\u00f3n ciudadana de Posadas se presentar\u00e1 ante funcionarios y expertos mundiales"},"content":{"rendered":"\n<p>Este martes se llev\u00f3 adelante la inauguraci\u00f3n del Primer Congreso Internacional de Participaci\u00f3n Ciudadana y Descentralizaci\u00f3n del que forma parte el Secretario de Planificaci\u00f3n Estrat\u00e9gica y Territorial, Diego Paredes, en representaci\u00f3n de la Municipalidad de Posadas. El evento que congrega a funcionarios, especialistas, acad\u00e9micos y expertos de todo el mundo se desarrollar\u00e1 hasta el jueves en la ciudad de C\u00f3rdoba.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-25-at-19.14.35-1024x682.jpeg\" alt=\"\" class=\"wp-image-7986\" srcset=\"https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-25-at-19.14.35-1024x682.jpeg 1024w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-25-at-19.14.35-300x200.jpeg 300w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-25-at-19.14.35-768x512.jpeg 768w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-25-at-19.14.35-1536x1023.jpeg 1536w, https:\/\/radionewsmisiones.ar\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-25-at-19.14.35.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>M\u00e1s de 100 expositores, panelistas y disertantes participan de este c\u00f3nclave mundial para brindar su visi\u00f3n y vivencias sobre la b\u00fasqueda de pol\u00edticas p\u00fablicas m\u00e1s efectivas en el gobierno local, participativo y descentralizado.<\/p>\n\n\n\n<p>El Secretario de Planificaci\u00f3n disertar\u00e1 este mi\u00e9rcoles, desde las 14:00 hs, exponiendo el modelo y la experiencia del municipio como referencia para otras ciudades de Am\u00e9rica Latina. \u201cLa capital misionera es tomada como referencia por la descentralizaci\u00f3n a trav\u00e9s de los Centros de Atenci\u00f3n al Vecino y las 11 delegaciones, como centros de operaciones y gestiones\u201d, resalt\u00f3 previo a su presentaci\u00f3n. Coment\u00f3 que: \u201cAbogamos por una ciudad donde el Estado est\u00e9 cerca del barrio, donde se puedan realizar la mayor\u00eda de los tr\u00e1mites administrativos, consultas y sugerencias. Queremos brindar soluciones, respuestas eficientes y \u00e1giles, porque estamos al servicio del pueblo para fortalecer la relaci\u00f3n Estado-ciudadano\u201d.<\/p>\n\n\n\n<p>Paredes tambi\u00e9n expondr\u00e1 sobre experiencias y pr\u00e1cticas ejecutadas por la Comuna posade\u00f1a en donde se aplicaron procesos de participaci\u00f3n ciudadana y descentralizaci\u00f3n. Entre ellos, el Presupuesto Participativo que involucra el trabajo colaborativo junto a los vecinos para mejorar sus realidades. Ponderando los casos que involucraron el debate social y cultural y soluciones innovadoras en cuanto a salud y bienestar, medio ambiente, educaci\u00f3n y aprendizaje, inclusi\u00f3n y empoderamiento, entre otros aspectos. Tambi\u00e9n el desarrollo costero en la zona de Miguel Lan\u00fas, crecimiento de las ofertas tur\u00edsticas, gastron\u00f3micas, inmobiliarias, la puesta en valor de espacios verdes y la importancia de la econom\u00eda del conocimiento.<\/p>\n\n\n\n<p>Vale mencionar que la gesti\u00f3n del intendente Leonardo Stelatto se propone una nueva forma de pensar la capital misionera, de manera descentralizada, participativa y planificada, con el fin de mejorar el nivel de gobernabilidad y la calidad de vida de las familias posade\u00f1as.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes se llev&oacute; adelante la inauguraci&oacute;n del Primer Congreso Internacional de Participaci&oacute;n Ciudadana y Descentralizaci&oacute;n del que forma parte el Secretario de Planificaci&oacute;n Estrat&eacute;gica y Territorial, Diego Paredes, en&hellip; <\/p>\n","protected":false},"author":3,"featured_media":7987,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[3],"tags":[22],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7985"}],"collection":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/comments?post=7985"}],"version-history":[{"count":1,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7985\/revisions"}],"predecessor-version":[{"id":7988,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/posts\/7985\/revisions\/7988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media\/7987"}],"wp:attachment":[{"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/media?parent=7985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/categories?post=7985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionewsmisiones.ar\/site\/wp-json\/wp\/v2\/tags?post=7985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}